{"id":28812,"date":"2026-08-08T10:00:00","date_gmt":"2026-08-08T01:00:00","guid":{"rendered":"https:\/\/www.shimamura.co.jp\/update\/shops\/ogaki\/winds\/28812\/"},"modified":"2026-08-08T10:00:00","modified_gmt":"2026-08-08T01:00:00","slug":"ogaki_8474","status":"publish","type":"shops","link":"https:\/\/www.shimamura.co.jp\/update\/shops\/ogaki\/winds\/28812\/","title":{"rendered":"\u30109\/5(\u571f)\u301c9\/13(\u65e5)\u3011\u5439\u594f\u697d\u304b\u3089\u5927\u4eba\u306e\u8da3\u5473\u307e\u3067\u5fb9\u5e95\u30b5\u30dd\u30fc\u30c8\uff01YAMAHA\u7ba1\u697d\u5668\u30d5\u30a7\u30a2\u958b\u50ac\uff01"},"content":{"rendered":" <figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/www.shimamura.co.jp\/shop\/ogaki\/wp-content\/uploads\/sites\/117\/2026\/07\/20260731-10cadc27d71f1efb9c3670cf395abb0a.jpg\" alt=\"\" class=\"wp-image-8531\"\/><\/figure>   <p class=\"wp-block-paragraph\">\u697d\u5668\u9078\u3073\u306e\u6c7a\u5b9a\u7248\uff01\u521d\u5fc3\u8005\u304b\u3089\u90e8\u6d3b\u751f\u3001\u3053\u3060\u308f\u308a\u3092\u6301\u3064\u4e0a\u7d1a\u8005\u307e\u3067\u3001\u5727\u5012\u7684\u306a\u652f\u6301\u3092\u96c6\u3081\u308b<strong>\u30e4\u30de\u30cf\uff08YAMAHA\uff09\u306e\u4eba\u6c17\u30e2\u30c7\u30eb<\/strong>\u304c\u4e00\u6319\u96c6\u7d50\u3059\u308b\u300c\u30e4\u30de\u30cf\u7ba1\u697d\u5668\u30d5\u30a7\u30a2\u300d\u3092\u958b\u50ac\u3044\u305f\u3057\u307e\u3059\u3002<\/p>   <p class=\"wp-block-paragraph\">\u5b9f\u969b\u306b\u300c\u898b\u3066\u300d\u300c\u89e6\u3063\u3066\u300d\u300c\u5439\u304d\u6bd4\u3079\u3089\u308c\u308b\u300d\u7d76\u597d\u306e\u30c1\u30e3\u30f3\u30b9\u3067\u3059\u3002\u7686\u69d8\u306e\u3054\u6765\u5e97\u3092\u5fc3\u3088\u308a\u304a\u5f85\u3061\u3057\u3066\u304a\u308a\u307e\u3059\uff01<\/p>   <h2 class=\"wp-block-heading\">\u30d5\u30a7\u30a2\u8a73\u7d30<\/h2>  <div class=\"tableBox\"><figure class=\"wp-block-table\"><table><tbody><tr><th>\u958b\u50ac\u671f\u9593<br \/>\n<\/th><td>9\/5\uff08\u571f\uff09\uff5e9\/13\uff08\u65e5\uff09<\/td><\/tr><tr><th>\u958b\u50ac\u6642\u9593<\/th><td>9\uff1a30\uff5e21\uff1a30<\/td><\/tr><tr><th>\u5834\u6240<\/th><td>\u5e97\u5185\u3000\u7ba1\u697d\u5668\u30b3\u30fc\u30ca\u30fc<\/td><\/tr><tr><th>\u304a\u554f\u3044\u5408\u308f\u305b<\/th><td>0584-77-1620<\/td><\/tr><tr><th>\u62c5\u5f53<\/th><td>\u5927\u897f\uff08\u304a\u304a\u306b\u3057\uff09<\/td><\/tr><\/tbody><\/table><\/figure><\/div>  <p class=\"wp-block-paragraph\">\u8a66\u594f\u306b\u3064\u3044\u3066\uff1a\u5e97\u8217\u3067\u306e\u8cb8\u51fa\u7528\u30de\u30a6\u30b9\u30d4\u30fc\u30b9\u3067\u306e\u8a66\u594f\u3082\u53ef\u80fd\u3067\u3059\u304c\u3001\u3054\u81ea\u8eab\u306e\u30de\u30a6\u30b9\u30d4\u30fc\u30b9\u3067\u304a\u8a66\u3057\u3044\u305f\u3060\u304f\u3053\u3068\u3092\u304a\u3059\u3059\u3081\u3044\u305f\u3057\u307e\u3059\uff01<br>\u30ea\u30fc\u30c9\u697d\u5668\u3092\u3054\u8a66\u594f\u306e\u65b9\u306f\u30ea\u30fc\u30c9\u4ee3\u3092\u9802\u6234\u3044\u305f\u3057\u307e\u3059\u3002\u304a\u6301\u3061\u306e\u65b9\u306f\u3054\u6301\u53c2\u304f\u3060\u3055\u3044\u3002<\/p>   <h2 class=\"wp-block-heading\">\u4eca\u56de\u306e\u6ce8\u76ee\u30e9\u30a4\u30f3\u30ca\u30c3\u30d7<\/h2>   <p class=\"wp-block-paragraph\">\u30d5\u30a7\u30a2\u671f\u9593\u4e2d\u306b\u5e97\u982d\u3067\u3054\u8a66\u594f\u3044\u305f\u3060\u3051\u308b\u3001\u53b3\u9078\u3055\u308c\u305f\u30e4\u30de\u30cf\u306e\u4eba\u6c17\u30e2\u30c7\u30eb\u3092\u3054\u7d39\u4ecb\u3057\u307e\u3059\u3002<\/p>   <h3 class=\"wp-block-heading\">\u30db\u30eb\u30f3\uff08Horn\uff09<\/h3>  <div class=\"imgBox\">\n\t<div class=\"photoBox\">\n\t\t<img decoding=\"async\" src=\"https:\/\/www.shimamura.co.jp\/shop\/wp-content\/uploads\/sites\/117\/2026\/07\/20260710-yhr-567d.jpg\" alt=\"YAMAHAYHR-567D\">\n\t<\/div>\n\t<div class=\"textBox\">\n\t\t<p class=\"ttl exclude-count\">YAMAHA<span>YHR-567D<\/span><\/p>\n\t\t<p class=\"exclude-count\"><\/p>\n\t\t<p class=\"pri exclude-count\"><span class=\"sml01\">\u00a5<\/span>485,100<span class=\"sml02\">\u7a0e\u8fbc<\/span><\/p>\n\t\t<div class=\"comLink\"><a href=\"https:\/\/jp.yamaha.com\/products\/musical_instruments\/winds\/frenchhorns\/yhr-567\/index.html\">\u5546\u54c1\u8a73\u7d30<\/a><\/div>\t<\/div>\n<\/div>\n <div class=\"imgBox\">\n\t<div class=\"photoBox\">\n\t\t<img decoding=\"async\" src=\"https:\/\/www.shimamura.co.jp\/shop\/wp-content\/uploads\/sites\/117\/2026\/07\/20260710-yhr-567gdb.jpg\" alt=\"YAMAHAYHR-567GDB\">\n\t<\/div>\n\t<div class=\"textBox\">\n\t\t<p class=\"ttl exclude-count\">YAMAHA<span>YHR-567GDB<\/span><\/p>\n\t\t<p class=\"exclude-count\"><\/p>\n\t\t<p class=\"pri exclude-count\"><span class=\"sml01\">\u00a5<\/span>554,400<span class=\"sml02\">\u7a0e\u8fbc<\/span><\/p>\n\t\t<div class=\"comLink\"><a href=\"https:\/\/jp.yamaha.com\/products\/musical_instruments\/winds\/frenchhorns\/yhr-567gdb\/index.html\">\u5546\u54c1\u8a73\u7d30<\/a><\/div>\t<\/div>\n<\/div>\n  <h3 class=\"wp-block-heading\">\u30e6\u30fc\u30d5\u30a9\u30cb\u30a2\u30e0\uff08Euphonium\uff09<\/h3>  <div class=\"imgBox\">\n\t<div class=\"photoBox\">\n\t\t<img decoding=\"async\" src=\"https:\/\/www.shimamura.co.jp\/shop\/wp-content\/uploads\/sites\/117\/2026\/07\/20260710-yep-621s-1-2.jpg\" alt=\"YAMAHAYEP-621S\">\n\t<\/div>\n\t<div class=\"textBox\">\n\t\t<p class=\"ttl exclude-count\">YAMAHA<span>YEP-621S<\/span><\/p>\n\t\t<p class=\"exclude-count\"><\/p>\n\t\t<p class=\"pri exclude-count\"><span class=\"sml01\">\u00a5<\/span>572,000<span class=\"sml02\">\u7a0e\u8fbc<\/span><\/p>\n\t\t<div class=\"comLink\"><a href=\"https:\/\/jp.yamaha.com\/products\/musical_instruments\/winds\/euphoniums\/yep-621s\/index.html\">\u5546\u54c1\u8a73\u7d30<\/a><\/div>\t<\/div>\n<\/div>\n <div class=\"imgBox\">\n\t<div class=\"photoBox\">\n\t\t<img decoding=\"async\" src=\"https:\/\/www.shimamura.co.jp\/shop\/wp-content\/uploads\/sites\/117\/2026\/07\/20260710-yep-642s.jpg\" alt=\"YAMAHAYEP-642S\">\n\t<\/div>\n\t<div class=\"textBox\">\n\t\t<p class=\"ttl exclude-count\">YAMAHA<span>YEP-642S<\/span><\/p>\n\t\t<p class=\"exclude-count\"><\/p>\n\t\t<p class=\"pri exclude-count\"><span class=\"sml01\">\u00a5<\/span>836,000<span class=\"sml02\">\u7a0e\u8fbc<\/span><\/p>\n\t\t<div class=\"comLink\"><a href=\"https:\/\/jp.yamaha.com\/products\/musical_instruments\/winds\/euphoniums\/yep-642s\/index.html\">\u5546\u54c1\u8a73\u7d30<\/a><\/div>\t<\/div>\n<\/div>\n  <h3 class=\"wp-block-heading\">\u30d0\u30ea\u30c8\u30f3\u30b5\u30af\u30bd\u30d5\u30a9\u30f3\uff08Baritone Saxophone\uff09<\/h3>  <div class=\"imgBox\">\n\t<div class=\"photoBox\">\n\t\t<img decoding=\"async\" src=\"https:\/\/www.shimamura.co.jp\/shop\/wp-content\/uploads\/sites\/117\/2026\/07\/20260710-ybs-480.jpg\" alt=\"YAMAHAYBS-480\">\n\t<\/div>\n\t<div class=\"textBox\">\n\t\t<p class=\"ttl exclude-count\">YAMAHA<span>YBS-480<\/span><\/p>\n\t\t<p class=\"exclude-count\"><\/p>\n\t\t<p class=\"pri exclude-count\"><span class=\"sml01\">\u00a5<\/span>623,700<span class=\"sml02\">\u7a0e\u8fbc<\/span><\/p>\n\t\t<div class=\"comLink\"><a href=\"https:\/\/jp.yamaha.com\/products\/musical_instruments\/winds\/saxophones\/ybs-480\/index.html\">\u5546\u54c1\u8a73\u7d30<\/a><\/div>\t<\/div>\n<\/div>\n <div class=\"imgBox\">\n\t<div class=\"photoBox\">\n\t\t<img decoding=\"async\" src=\"https:\/\/www.shimamura.co.jp\/shop\/wp-content\/uploads\/sites\/117\/2026\/07\/20260710-ybs-62.jpg\" alt=\"YAMAHAYBS-62\">\n\t<\/div>\n\t<div class=\"textBox\">\n\t\t<p class=\"ttl exclude-count\">YAMAHA<span>YBS-62<\/span><\/p>\n\t\t<p class=\"exclude-count\"><\/p>\n\t\t<p class=\"pri exclude-count\"><span class=\"sml01\">\u00a5<\/span>1,039,500<span class=\"sml02\">\u7a0e\u8fbc<\/span><\/p>\n\t\t<div class=\"comLink\"><a href=\"https:\/\/jp.yamaha.com\/products\/musical_instruments\/winds\/saxophones\/ybs-62_03\/index.html\">\u5546\u54c1\u8a73\u7d30<\/a><\/div>\t<\/div>\n<\/div>\n  <h3 class=\"wp-block-heading\">\u30aa\u30fc\u30dc\u30a8\uff08Oboe\uff09<\/h3>  <div class=\"imgBox\">\n\t<div class=\"photoBox\">\n\t\t<img decoding=\"async\" src=\"https:\/\/www.shimamura.co.jp\/shop\/wp-content\/uploads\/sites\/117\/2026\/07\/20260710-yob-431-2-1.jpg\" alt=\"YAMAHAYOB-431\">\n\t<\/div>\n\t<div class=\"textBox\">\n\t\t<p class=\"ttl exclude-count\">YAMAHA<span>YOB-431<\/span><\/p>\n\t\t<p class=\"exclude-count\"><\/p>\n\t\t<p class=\"pri exclude-count\"><span class=\"sml01\">\u00a5<\/span>455,400<span class=\"sml02\">\u7a0e\u8fbc<\/span><\/p>\n\t\t<div class=\"comLink\"><a href=\"https:\/\/jp.yamaha.com\/products\/musical_instruments\/winds\/oboes\/yob-431_432\/index.html\">\u5546\u54c1\u8a73\u7d30<\/a><\/div>\t<\/div>\n<\/div>\n <div class=\"imgBox\">\n\t<div class=\"photoBox\">\n\t\t<img decoding=\"async\" src=\"https:\/\/www.shimamura.co.jp\/shop\/wp-content\/uploads\/sites\/117\/2026\/07\/20260710-yob-432jpg-1-2.jpg\" alt=\"YAMAHAYOB-432\">\n\t<\/div>\n\t<div class=\"textBox\">\n\t\t<p class=\"ttl exclude-count\">YAMAHA<span>YOB-432<\/span><\/p>\n\t\t<p class=\"exclude-count\"><\/p>\n\t\t<p class=\"pri exclude-count\"><span class=\"sml01\">\u00a5<\/span>495,000<span class=\"sml02\">\u7a0e\u8fbc<\/span><\/p>\n\t\t<div class=\"comLink\"><a href=\"https:\/\/jp.yamaha.com\/products\/musical_instruments\/winds\/oboes\/yob-431_432\/index.html\">\u5546\u54c1\u8a73\u7d30<\/a><\/div>\t<\/div>\n<\/div>\n  <h3 class=\"wp-block-heading\">\u30c1\u30e5\u30fc\u30d0\uff08Tuba\uff09<\/h3>  <div class=\"imgBox\">\n\t<div class=\"photoBox\">\n\t\t<img decoding=\"async\" src=\"https:\/\/www.shimamura.co.jp\/shop\/wp-content\/uploads\/sites\/117\/2026\/07\/20260710-ybb-621-1.jpg\" alt=\"YAMAHAYBB-621\">\n\t<\/div>\n\t<div class=\"textBox\">\n\t\t<p class=\"ttl exclude-count\">YAMAHA<span>YBB-621<\/span><\/p>\n\t\t<p class=\"exclude-count\"><\/p>\n\t\t<p class=\"pri exclude-count\"><span class=\"sml01\">\u00a5<\/span>1,089,000<span class=\"sml02\">\u7a0e\u8fbc<\/span><\/p>\n\t\t<div class=\"comLink\"><a href=\"https:\/\/jp.yamaha.com\/products\/musical_instruments\/winds\/tubas\/ybb-621\/index.html\">\u5546\u54c1\u8a73\u7d30<\/a><\/div>\t<\/div>\n<\/div>\n <div class=\"imgBox\">\n\t<div class=\"photoBox\">\n\t\t<img decoding=\"async\" src=\"https:\/\/www.shimamura.co.jp\/shop\/wp-content\/uploads\/sites\/117\/2026\/07\/20260710-ybb-642ii-1.jpg\" alt=\"YAMAHAYBB-641\u2161\">\n\t<\/div>\n\t<div class=\"textBox\">\n\t\t<p class=\"ttl exclude-count\">YAMAHA<span>YBB-641\u2161<\/span><\/p>\n\t\t<p class=\"exclude-count\"><\/p>\n\t\t<p class=\"pri exclude-count\"><span class=\"sml01\">\u00a5<\/span>1,199,000<span class=\"sml02\">\u7a0e\u8fbc<\/span><\/p>\n\t\t<div class=\"comLink\"><a href=\"https:\/\/jp.yamaha.com\/products\/musical_instruments\/winds\/tubas\/ybb-641ii\/index.html\">\u5546\u54c1\u8a73\u7d30<\/a><\/div>\t<\/div>\n<\/div>\n  <h2 class=\"wp-block-heading\">\u305d\u306e\u4ed6\u5c55\u793a\u7ba1\u697d\u5668\u306f\u30aa\u30f3\u30e9\u30a4\u30f3\u30b9\u30c8\u30a2\u306b\u3066\u516c\u958b\u3057\u3066\u304a\u308a\u307e\u3059\uff01<\/h2>   <p class=\"wp-block-paragraph\">\u30a2\u30af\u30a2\u30a6\u30a9\u30fc\u30af\u5927\u57a3\u5e97\u3067\u5c55\u793a\u3057\u3066\u3044\u308b\u7ba1\u697d\u5668\u306f\u30aa\u30f3\u30e9\u30a4\u30f3\u30b9\u30c8\u30a2\u306b\u3066\u63b2\u8f09\u3057\u3066\u304a\u308a\u307e\u3059\uff01<br>\u5c55\u793a\u697d\u5668\u306e\u5199\u771f\u3082\u63b2\u8f09\u3057\u3066\u304a\u308a\u307e\u3059\u306e\u3067\u3054\u89a7\u304f\u3060\u3055\u3044\uff01<\/p>  <div class=\"d-flex justify-content-center\">\n    <a href=\"https:\/\/store.shimamura.co.jp\/ec\/Facet?category_0=11160000000&#038;inputKeywordFacet=%E5%A4%A7%E5%9E%A3&#038;kclsf=AND\" class=\"btn btn-default fs-16 fs-md-18 px-60 px-lg-100 py-10 py-md-15 rounded-3 d-flex justify-content-center align-items-center\">\n        <span>\u30aa\u30f3\u30e9\u30a4\u30f3\u30b9\u30c8\u30a2\u306f\u3053\u3061\u3089<\/span>\n        <svg class=\"icon\" width=\"32\" height=\"32\" role=\"img\"><use href=\"https:\/\/www.shimamura.co.jp\/update\/wp-content\/themes\/update\/frontend\/icons.svg#bi-arrow-right-short\"><\/use><\/svg>    <\/a>\n<\/div>\n\n\n  <h2 class=\"wp-block-heading\">\u3054\u6765\u5e97\u4e88\u7d04\u30fb\u304a\u554f\u3044\u5408\u308f\u305b\u306f\u3053\u3061\u3089\u304b\u3089<\/h2>  <div class=\"tableBox\"><figure class=\"wp-block-table\"><table><tbody><tr><th>TEL<\/th><td>0584-77-1620<\/td><\/tr><tr><th>\u62c5\u5f53<\/th><td>\u5927\u897f\uff08\u304a\u304a\u306b\u3057\uff09<\/td><\/tr><\/tbody><\/table><\/figure><\/div> <div class=\"d-flex justify-content-center\">\n    <a href=\"\" class=\"btn btn-default fs-16 fs-md-18 px-60 px-lg-100 py-10 py-md-15 rounded-3 d-flex justify-content-center align-items-center\">\n        <span>\u3054\u6765\u5e97\u4e88\u7d04\u30d5\u30a9\u30fc\u30e0<\/span>\n        <svg class=\"icon\" width=\"32\" height=\"32\" role=\"img\"><use href=\"https:\/\/www.shimamura.co.jp\/update\/wp-content\/themes\/update\/frontend\/icons.svg#bi-arrow-right-short\"><\/use><\/svg>    <\/a>\n<\/div>\n\n\n  <p class=\"wp-block-paragraph\"><\/p> ","protected":false},"excerpt":{"rendered":"<p>\u697d\u5668\u9078\u3073\u306e\u6c7a\u5b9a\u7248\uff01\u521d\u5fc3\u8005\u304b\u3089\u90e8\u6d3b\u751f\u3001\u3053\u3060\u308f\u308a\u3092\u6301\u3064\u4e0a\u7d1a\u8005\u307e\u3067\u3001\u5727\u5012\u7684\u306a\u652f\u6301\u3092\u96c6\u3081\u308b\u30e4\u30de\u30cf\uff08YAMAHA\uff09\u306e\u4eba\u6c17\u30e2\u30c7\u30eb\u304c\u4e00\u6319\u96c6\u7d50\u3059\u308b\u300c\u30e4\u30de\u30cf\u7ba1\u697d\u5668\u30d5\u30a7\u30a2\u300d\u3092\u958b\u50ac\u3044\u305f\u3057\u307e\u3059\u3002 \u5b9f\u969b\u306b\u300c\u898b\u3066\u300d\u300c\u89e6\u3063\u3066\u300d\u300c\u5439\u304d\u6bd4\u3079\u3089\u308c\u308b\u300d\u7d76\u597d\u306e [&hellip;]<\/p>\n","protected":false},"author":131,"featured_media":28813,"template":"","meta":[],"categories":[9],"common":[379],"class_list":["post-28812","shops","type-shops","status-publish","has-post-thumbnail","hentry","category-winds","common-shop-item"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.shimamura.co.jp\/update\/wp-json\/wp\/v2\/shops\/28812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.shimamura.co.jp\/update\/wp-json\/wp\/v2\/shops"}],"about":[{"href":"https:\/\/www.shimamura.co.jp\/update\/wp-json\/wp\/v2\/types\/shops"}],"author":[{"embeddable":true,"href":"https:\/\/www.shimamura.co.jp\/update\/wp-json\/wp\/v2\/users\/131"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.shimamura.co.jp\/update\/wp-json\/wp\/v2\/media\/28813"}],"wp:attachment":[{"href":"https:\/\/www.shimamura.co.jp\/update\/wp-json\/wp\/v2\/media?parent=28812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.shimamura.co.jp\/update\/wp-json\/wp\/v2\/categories?post=28812"},{"taxonomy":"common","embeddable":true,"href":"https:\/\/www.shimamura.co.jp\/update\/wp-json\/wp\/v2\/common?post=28812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}